{"id":16671,"date":"2025-07-11T15:09:30","date_gmt":"2025-07-11T07:09:30","guid":{"rendered":"https:\/\/xiairworld.com\/?page_id=16671"},"modified":"2026-06-04T17:28:07","modified_gmt":"2026-06-04T09:28:07","slug":"muebles-de-exterior-preescolares","status":"publish","type":"page","link":"https:\/\/xiairworld.com\/es_mx\/preschool-outdoor-furniture\/","title":{"rendered":"Muebles de exterior para preescolares"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16671\" class=\"elementor elementor-16671\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f8816d elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"7f8816d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ac3cd7d\" data-id=\"ac3cd7d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adb37af elementor-widget elementor-widget-elementskit-heading\" data-id=\"adb37af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">Outdoor Furniture  for Play Spaces<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>We manufacture and supply durable outdoor furniture for children\u2019s learning, play, storage, and daily outdoor activities.<\/p>\n<p>We can assist you in selecting the right furniture, customizing details to suit your specific space, and fulfilling your order with comprehensive project support.<\/p>\n<p><!-- notionvc: 095f0a59-9da4-4570-b74d-dd97c73b82e3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-688092c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"688092c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Weather resistant materials<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stable structure<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Smooth edges and easy clean surfaces<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Functional designs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lower maintenance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53b43ef elementor-align-left elementor-widget elementor-widget-button\" data-id=\"53b43ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExMDAyIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get a Free Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13022ec\" data-id=\"13022ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9b815b elementor-widget elementor-widget-spacer\" data-id=\"d9b815b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02f9cae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02f9cae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-332d120\" data-id=\"332d120\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5c3962 elementor-widget elementor-widget-elementskit-heading\" data-id=\"c5c3962\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Outdoor Furniture Categories<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>We offer a diverse range of outdoor furniture options that can be tailored to suit specific space dimensions, age groups, intended activities, and project aesthetics. Each product category is designed with specific functions and structural features to effectively fulfill the requirements of daily outdoor use.<!-- notionvc: 25815b26-17e1-4288-9c82-a5304d29c617 --><br \/><!-- notionvc: 7d713027-281a-4ec3-aa9e-3eaf373f7516 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-120afd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"120afd0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ce56ad0\" data-id=\"ce56ad0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78f1cc7 elementor-widget elementor-widget-elementskit-heading\" data-id=\"78f1cc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">Outdoor Tables and Chairs<\/h3>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Our outdoor tables and chairs are designed with child sized proportions, stable legs, smooth surfaces, and practical heights for daily use. The primary value of such products lies in supporting activities; they help transform open outdoor areas into usable learning spaces.<!-- notionvc: 9e5c8519-4b21-4b88-816d-de7f65fc4440 --><br \/><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f26c87 uael-img-grid__column-4 uael-img-grid-tablet__column-3 uael-img-grid-mobile__column-2 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"6f26c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;gallery_columns&quot;:&quot;4&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;gallery_columns_mobile&quot;:&quot;2&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption-on-image uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img fetchpriority=\"high\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table.webp\" class=\"attachment-full size-full wp-image-20559\" alt=\"Classroom Outdoor Table\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Classroom-Outdoor-Table-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Classroom Outdoor Table<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches.webp\" class=\"attachment-full size-full wp-image-20556\" alt=\"Infant Table and Benches\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Infant-Table-and-Benches-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Infant Table and Benches<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set.webp\" class=\"attachment-full size-full wp-image-20558\" alt=\"Square Table &amp; Bench Set\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Square-Table-Bench-Set-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Square Table &amp; Bench Set<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set.webp\" class=\"attachment-full size-full wp-image-20563\" alt=\"Large Outdoor Table And Bench Set\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Large-Outdoor-Table-And-Bench-Set-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Large Outdoor Table And Bench Set<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench.webp\" class=\"attachment-full size-full wp-image-20557\" alt=\"Outdoor Buddy Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Buddy-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Buddy Bench<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set.webp\" class=\"attachment-full size-full wp-image-20561\" alt=\"Picnic Table Beer Bench Set\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Picnic-Table-Beer-Bench-Set-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Picnic Table Beer Bench Set<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-7\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set.webp\" class=\"attachment-full size-full wp-image-20560\" alt=\"Outdoor Craft Table Benches Set\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Craft-Table-Benches-Set-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Craft Table Benches Set<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-8\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set.webp\" class=\"attachment-full size-full wp-image-20562\" alt=\"Rattan Wicker Table Set\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Rattan-Wicker-Table-Set-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Rattan Wicker Table Set<\/div><\/div><\/figcaption><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d08f45d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d08f45d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExMDAyIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More Products<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c4b5c47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4b5c47\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4427b0a\" data-id=\"4427b0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c64d468 elementor-widget elementor-widget-elementskit-heading\" data-id=\"c64d468\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">Outdoor Benches and Seating<\/h3>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Our range of outdoor benches and seating is designed to provide robust, continuous support while optimizing space efficiency. Compared to individual chairs, benches offer a cleaner furniture layout and are easier to manage within expansive outdoor environments.<!-- notionvc: ddd53f85-c6cd-4d78-881c-d9f66bc0a1ff --><br \/><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f94bed uael-img-grid__column-6 uael-img-grid-tablet__column-3 uael-img-grid-mobile__column-2 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"2f94bed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;gallery_columns&quot;:&quot;6&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;gallery_columns_mobile&quot;:&quot;2&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption-on-image uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench.webp\" class=\"attachment-full size-full wp-image-20564\" alt=\"Outdoor Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Bench<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench.webp\" class=\"attachment-full size-full wp-image-20566\" alt=\"Small Outdoor Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Small-Outdoor-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Small Outdoor Bench<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table.webp\" class=\"attachment-full size-full wp-image-20567\" alt=\"Kids Outdoor Table\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Kids-Outdoor-Table-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Kids Outdoor Table<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench.webp\" class=\"attachment-full size-full wp-image-20568\" alt=\"Buddy Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Buddy-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Buddy Bench<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench.webp\" class=\"attachment-full size-full wp-image-20569\" alt=\"Preschool Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Preschool-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Preschool Bench<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench.webp\" class=\"attachment-full size-full wp-image-20565\" alt=\"Playground Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Playground-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Playground Bench<\/div><\/div><\/figcaption><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0af9802 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0af9802\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExMDAyIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More Products<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e7392ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7392ea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-628500c\" data-id=\"628500c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f6a73a elementor-widget elementor-widget-elementskit-heading\" data-id=\"5f6a73a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">Outdoor Storage Furniture<\/h3>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Our outdoor storage furniture prioritizes organization, item protection, and convenient access. Features such as raised bases, smooth surfaces, and weather-resistant finishes ensure long-term durability while preventing items from becoming scattered.<!-- notionvc: 2e07760d-5fe2-4695-b1fa-1a52c2b16fb2 --><br \/><!-- notionvc: 614c253d-d3dd-4fc0-a75f-c5a4feafc342 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47a2c96 uael-img-grid__column-6 uael-img-grid-tablet__column-3 uael-img-grid-mobile__column-2 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"47a2c96\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;gallery_columns&quot;:&quot;6&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;gallery_columns_mobile&quot;:&quot;2&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption-on-image uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf.webp\" class=\"attachment-full size-full wp-image-20575\" alt=\"Outdoor Rolling Storage Shelf\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Rolling-Storage-Shelf-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Rolling Storage Shelf<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf.webp\" class=\"attachment-full size-full wp-image-20574\" alt=\"Outdoor Storage Shelf\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shelf-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Storage Shelf<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench.webp\" class=\"attachment-full size-full wp-image-20573\" alt=\"Wooden Storage Bench\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Storage-Bench-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Wooden Storage Bench<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage.webp\" class=\"attachment-full size-full wp-image-20571\" alt=\"Wooden Tilted Tray Storage\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Wooden-Tilted-Tray-Storage-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Wooden Tilted Tray Storage<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed.webp\" class=\"attachment-full size-full wp-image-20572\" alt=\"Outdoor Storage Shed\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Storage-Shed-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Storage Shed<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard.webp\" class=\"attachment-full size-full wp-image-20570\" alt=\"Outdoor Curiosity Cupboard\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Curiosity-Cupboard-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Curiosity Cupboard<\/div><\/div><\/figcaption><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e29183e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e29183e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExMDAyIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More Products<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d3695a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d3695a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-57d049e\" data-id=\"57d049e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e2aebf elementor-widget elementor-widget-elementskit-heading\" data-id=\"0e2aebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">Outdoor Art Furniture<\/h3>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Our outdoor art furniture prioritizes easy-to-clean surfaces and convenient material handling. Users can select from a range of movable panels, trays, and work surfaces tailored to specific applications, thereby accommodating a variety of hands-on activities without creating additional burdens.<!-- notionvc: 72390c11-5b40-4313-92cf-8fa07eec940d --><br \/><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-897cac2 uael-img-grid__column-6 uael-img-grid-tablet__column-3 uael-img-grid-mobile__column-2 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"897cac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;gallery_columns&quot;:&quot;6&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;gallery_columns_mobile&quot;:&quot;2&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption-on-image uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table.webp\" class=\"attachment-full size-full wp-image-20581\" alt=\"Outdoor Art Activity Table\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Activity-Table-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Art Activity Table<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic.webp\" class=\"attachment-full size-full wp-image-20576\" alt=\"Outdoor Activity Table with Acrylic\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Activity-Table-with-Acrylic-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Activity Table with Acrylic<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window.webp\" class=\"attachment-full size-full wp-image-20580\" alt=\"Outdoor Creative Painting Window\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Creative-Painting-Window-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Creative Painting Window<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel.webp\" class=\"attachment-full size-full wp-image-20579\" alt=\"Outdoor Art Easel\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Art-Easel-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Art Easel<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard.webp\" class=\"attachment-full size-full wp-image-20577\" alt=\"Framed Outdoor Chalkboard\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Framed-Outdoor-Chalkboard-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Framed Outdoor Chalkboard<\/div><\/div><\/figcaption><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel.webp\" class=\"attachment-full size-full wp-image-20578\" alt=\"Outdoor Wooden Seated Easel\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Wooden-Seated-Easel-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><figcaption class=\"uael-grid-img-content\"><div class=\"uael-grid-img-caption\"><div class=\"uael-grid-caption-text\">Outdoor Wooden Seated Easel<\/div><\/div><\/figcaption><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c294e34 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c294e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExMDAyIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More Products<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90cb427 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90cb427\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a9f8c6\" data-id=\"5a9f8c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d7f428 elementor-widget elementor-widget-elementskit-heading\" data-id=\"0d7f428\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Built for Outdoor Use, Not Just Outdoor Display<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Outdoor Furniture must perform well after months and years of use, not only look attractive on the first day. We focus on materials, finishes, and construction details that support long term outdoor performance.<\/p>\n<p>You can select our products based on climate, intended use, budget, and design style.<!-- notionvc: eb3e0d74-e94b-4730-a524-13f1bad995d3 --><!-- notionvc: 0d27928f-1f90-43f5-8b3d-55f229d3f5e4 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84be14a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84be14a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a6b31b9\" data-id=\"a6b31b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a718c7 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"6a718c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Weather Resistant Material Options                <\/div>\n                        \t\t  \t<p>Our outdoor furniture is crafted from corrosion-resistant materials and features protective coatings suitable for outdoor use, thereby minimizing premature cracking or deformation.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c66aac0\" data-id=\"c66aac0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee2d87e ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"ee2d87e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Treated Wood Options                <\/div>\n                        \t\t  \t<p>Our timber undergoes a multi-stage production process involving drying, sanding, anti-corrosion treatment, and the application of protective coatings. This process effectively preserves the wood's natural grain while simultaneously enhancing its moisture resistance.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f85eca9\" data-id=\"f85eca9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76db4f2 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"76db4f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Powder Coated Metal Options                <\/div>\n                        \t\t  \t<p>For furniture requiring enhanced structural support, the frames and support components are constructed from powder-coated metal. This enhances the furniture's resistance to abrasion and weathering without compromising its aesthetic appeal.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ca388fc\" data-id=\"ca388fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b38cf3f ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"b38cf3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Practical and Stable Structure                <\/div>\n                        \t\t  \t<p>Depending on the product type, we utilize thicker support panels, wider base contact surfaces, reinforced side frames, cross-bracing structures, and more secure fastening points to help the furniture maintain stability during repeated use.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa1586e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aa1586e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExMDAyIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More Products<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ae8741 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ae8741\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c703b8f\" data-id=\"c703b8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f340958 elementor-widget elementor-widget-elementskit-heading\" data-id=\"f340958\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Child Safe Details for Everyday Outdoor Play<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Outdoor furniture for young children needs careful attention to size, stability, touch, and movement. We design and select products with the daily habits of children in mind, helping reduce avoidable risks during active use.<!-- notionvc: 672da6da-fd12-44ce-8344-adc29d867cf4 --><br \/><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b8ad132 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8ad132\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-763ad19\" data-id=\"763ad19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9385ae5 elementor-widget elementor-widget-image\" data-id=\"9385ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Rounded-Edges.webp\" class=\"attachment-large size-large wp-image-20582\" alt=\"Outdoor Furniture Rounded Edges\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Rounded-Edges.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Rounded-Edges-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Rounded-Edges-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Rounded-Edges-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Rounded-Edges-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-372a7e3 elementor-widget elementor-widget-elementskit-heading\" data-id=\"372a7e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit-heading--title elementskit-section-title \">Rounded Edges<\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>We apply rounded corners and softened edges to key contact areas to minimize sharp contact points during movement and daily use.<!-- notionvc: ffff0151-15bc-48e9-a07b-3f6950910fcc --><br \/><!-- notionvc: 2cab9acd-5bd8-461d-a1de-504b9afe7be2 --><\/p>\n<p><!-- notionvc: a889ba20-8a44-4732-a638-d0aa89ad5113 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8911abd\" data-id=\"8911abd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f67885 elementor-widget elementor-widget-image\" data-id=\"0f67885\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Child-Scaled-Proportions.webp\" class=\"attachment-large size-large wp-image-20583\" alt=\"Child-Scaled Proportions\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Child-Scaled-Proportions.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Child-Scaled-Proportions-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Child-Scaled-Proportions-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Child-Scaled-Proportions-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Child-Scaled-Proportions-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa19d83 elementor-widget elementor-widget-elementskit-heading\" data-id=\"aa19d83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit-heading--title elementskit-section-title \">Child-Scaled Proportions<\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>We offer outdoor furniture with appropriate proportions that are tailored to the target age group, ensuring that children do not need to climb, stretch, or maintain unstable postures.<!-- notionvc: e15cff12-c189-48b6-9b2f-8f962b5c9e9d --><br \/><!-- notionvc: 96ec5ac8-205a-4fd1-836c-57f0dad9659c --><\/p>\n<p><!-- notionvc: a889ba20-8a44-4732-a638-d0aa89ad5113 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f48b75c\" data-id=\"f48b75c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1593538 elementor-widget elementor-widget-image\" data-id=\"1593538\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Smooth-Surface.webp\" class=\"attachment-large size-large wp-image-20584\" alt=\"Outdoor Furniture Smooth Surface\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Smooth-Surface.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Smooth-Surface-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Smooth-Surface-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Smooth-Surface-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Outdoor-Furniture-Smooth-Surface-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d5e885 elementor-widget elementor-widget-elementskit-heading\" data-id=\"0d5e885\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit-heading--title elementskit-section-title \">Smooth Surface<\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>The surfaces of our outdoor furniture are smooth and pleasant to the touch, minimizing splinters, rough edges, and discomfort.<!-- notionvc: 00c2230d-cf89-42f9-9d44-c3005405d2a8 --><br \/><!-- notionvc: 329ca700-678b-4c9e-b149-aea406b7b9f4 --><\/p>\n<p><!-- notionvc: a889ba20-8a44-4732-a638-d0aa89ad5113 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d70bef9\" data-id=\"d70bef9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8a90fb elementor-widget elementor-widget-image\" data-id=\"b8a90fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Safety-Hardware-and-Connections.webp\" class=\"attachment-large size-large wp-image-20585\" alt=\"Safety Hardware and Connections\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Safety-Hardware-and-Connections.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Safety-Hardware-and-Connections-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Safety-Hardware-and-Connections-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Safety-Hardware-and-Connections-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Safety-Hardware-and-Connections-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b79ea4b elementor-widget elementor-widget-elementskit-heading\" data-id=\"b79ea4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit-heading--title elementskit-section-title \">Safety Hardware and Connections<\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>We offer various installation and connection methods, utilizing embedded or concealed designs for screws and fittings.<!-- notionvc: 11df5256-c67e-4100-847c-4f4db6d61c0b --><br \/><!-- notionvc: 329ca700-678b-4c9e-b149-aea406b7b9f4 --><\/p>\n<p><!-- notionvc: a889ba20-8a44-4732-a638-d0aa89ad5113 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de21dac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de21dac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a17b42b\" data-id=\"a17b42b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c263d6c elementor-widget elementor-widget-elementskit-heading\" data-id=\"c263d6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Factory Finished Outdoor Furniture Showcase<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Prior to shipment, you have the opportunity to personally inspect the actual furniture produced at our factory. This allows you to gain a truly authentic perspective on the products' actual quality.<!-- notionvc: 20b6c074-e055-4ef7-b597-d8dce7886acc --><br \/><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e64652 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3e64652\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1. Actual finished products from the factory<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2. Clear illustration of product structure and surface finishes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3. Close-up details of outdoor furniture prior to packaging<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4. Product photographs for order confirmation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5. Packaging and shipping preparations<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-47190e2\" data-id=\"47190e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7324538 uael-img-grid__column-4 uael-img-grid-tablet__column-3 uael-img-grid-mobile__column-2 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"7324538\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;gallery_columns&quot;:&quot;4&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;gallery_columns_mobile&quot;:&quot;2&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption- uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs.webp\" class=\"attachment-full size-full wp-image-20586\" alt=\"factoyr Product photographs\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/factoyr-Product-photographs-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory.webp\" class=\"attachment-full size-full wp-image-20587\" alt=\"finished products from the factory\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/finished-products-from-the-factory-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture.webp\" class=\"attachment-full size-full wp-image-20588\" alt=\"Factory Finished Outdoor Furniture\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Factory-Finished-Outdoor-Furniture-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products.webp\" class=\"attachment-full size-full wp-image-20589\" alt=\"Xiair Factory Outdoor Products\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Factory-Outdoor-Products-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture.webp\" class=\"attachment-full size-full wp-image-20590\" alt=\"Xiair outdoor furniture\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-outdoor-furniture-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products.webp\" class=\"attachment-full size-full wp-image-20591\" alt=\"Xiair Outdoor Products\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Products-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-7\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set.webp\" class=\"attachment-full size-full wp-image-20592\" alt=\"Xiair Outdoor Furniture set\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Furniture-set-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-8\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table.webp\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" src=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table.webp\" class=\"attachment-full size-full wp-image-20593\" alt=\"Xiair Outdoor Table\" srcset=\"https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table.webp 801w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table-300x300.webp 300w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table-150x150.webp 150w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table-768x768.webp 768w, https:\/\/xiairworld.com\/wp-content\/uploads\/2026\/06\/Xiair-Outdoor-Table-12x12.webp 12w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cea35eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cea35eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2348750\" data-id=\"2348750\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6de371 elementor-widget elementor-widget-elementskit-heading\" data-id=\"c6de371\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Outdoor Layout Support<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Before you finalize your order, we will assist you in assessing your outdoor area. Based on your specific requirements, we can recommend suitable product combinations and layout arrangements.<!-- notionvc: 745d1689-6cf0-48a8-b248-f8eea143e4ff --><br \/><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7d75006 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d75006\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-35bf9d0\" data-id=\"35bf9d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-073c482 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"073c482\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Share Your Outdoor Space                <\/div>\n                        \t\t  \t<p>You can provide a floor plan, site photos, or a simple sketch. Our team will assess the available space and understand its intended use.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e6343f1\" data-id=\"e6343f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27c40f1 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"27c40f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Confirm Age Groups and Capacity                <\/div>\n                        \t\t  \t<p>Based on the age range and number of users, we recommend furniture with appropriate heights, dimensions, structures, and functions.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6e585a6\" data-id=\"6e585a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82be398 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"82be398\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Recommended Product Combinations                <\/div>\n                        \t\t  \t<p>We match furniture with various outdoor activity functions to curate a complete set of supplies for your entire space, thereby easing your design burden.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aea75ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aea75ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a41712\" data-id=\"3a41712\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2ce627 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"c2ce627\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Layout and Budget Adjustment                <\/div>\n                        \t\t  \t<p>We assist in distinguishing between essentials and optional accessories, enabling a more practical approach to planning your outdoor space while avoiding unnecessary purchases.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b4d3ab\" data-id=\"6b4d3ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ecd57e ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"8ecd57e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <div class=\"elementskit-info-box-title\">\n                    Pre-Production Detail Confirmation                <\/div>\n                        \t\t  \t<p>Verify specifications, materials, quantities, packaging details, and delivery information prior to the start of production to prevent errors during the order process.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-169f847 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"169f847\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b7e4a2\" data-id=\"8b7e4a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6928adf elementor-widget elementor-widget-elementskit-heading\" data-id=\"6928adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Plan Your Outdoor Furniture Project With Us<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Every outdoor space has different size limits, activity needs, material requirements, and budget considerations. Send us your project details, and our team will help you choose Outdoor Furniture that fits your space, use purpose, and purchasing plan.<\/p>\n<p>Whether you require a selection of products or a complete outdoor furniture solution, we can provide it for you.<!-- notionvc: ab16e5fe-6272-4a86-8151-24d916a5aaed --><!-- notionvc: 621c3a10-f1ea-4ebf-9c8f-0245b5d20f41 --><\/p>\n<p><!-- notionvc: 1aad9bc9-73f4-4d25-b78b-2251548e18d3 --><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9c78548 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c78548\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-28a4d40\" data-id=\"28a4d40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7804fac elementor-widget elementor-widget-elementskit-heading\" data-id=\"7804fac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"ekit-heading--title elementskit-section-title \">What You Can Send Us<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-608ba14 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"608ba14\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Outdoor area size or floor plan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Product types you are interested in<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Age group and expected number of children<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Preferred material, color, or style<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Project budget<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Delivery country or shipping requirement<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60ae522\" data-id=\"60ae522\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c72d817 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"c72d817\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_icon_shape&quot;:&quot;rounded&quot;,&quot;step_type&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Xiair Quote\" aria-label=\"Xiair Quote\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"16671\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c72d817\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Preschool Outdoor Furniture Professional Daycare Furniture Manufacturer\uff5cXiair World\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"16671\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-phone elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tPhone\/WhatsApp\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[phone]\" id=\"form-field-phone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Phone\/WhatsApp\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-location elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-location\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCountry \/ Region\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[location]\" id=\"form-field-location\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Country \/ Region\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-project_scale elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-project_scale\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tProject Scale\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[project_scale]\" id=\"form-field-project_scale\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">Project Scale <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 1 classroom\">1 classroom <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 2\u20133 classrooms\">2\u20133 classrooms <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 4\u20136 classrooms\">4\u20136 classrooms <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 7+ classrooms\">7+ classrooms <\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-project_type elementor-col-50 elementor-sm-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-project_type\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tProject Type\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[project_type]\" id=\"form-field-project_type\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\" \">Project Type <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" New daycare opening\">New daycare opening <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Existing daycare renovation\">Existing daycare renovation <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Classroom expansion\">Classroom expansion <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Multiple locations \/ chain project\">Multiple locations \/ chain project <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Distributor \/ project partner\">Distributor \/ project partner <\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"2\" placeholder=\"You may share number of students, classroom size, age groups, preferred materials, or any special requirements.\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Start Your Outdoor Project<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-146b53e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"146b53e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f14ff5f\" data-id=\"f14ff5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe60b5c elementor-widget elementor-widget-elementskit-heading\" data-id=\"fe60b5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Q&amp;A<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60807b5 uael-faq-box-layout-yes align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"60807b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-101' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"accordion\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-54aa716\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-54aa716 uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a975405cd3bb\">Q1: What is the difference between indoor furniture and outdoor furniture?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Outdoor furniture needs stronger resistance to changing environments and more practical surface treatment. Indoor furniture is usually not designed to handle moisture, direct sunlight, dust, and frequent outdoor cleaning.<!-- notionvc: e8a8aee4-9867-4bd4-96cd-1d33ad021c00 --><br \/><!-- notionvc: 5b7875b8-e130-4f12-a66f-6cbfa66bdaac --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-4b42895\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-4b42895 uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a975405cd4d1\">Q2: Can outdoor furniture stay outside all year?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>This depends on the material, local climate, and how the furniture is maintained. Some outdoor furniture can remain outside for long periods, while some products may last longer if placed under shade, covered during heavy rain, or stored during extreme weather.<!-- notionvc: 9ee730c6-d868-41ad-8305-389adb569d0b --><br \/><!-- notionvc: 788326fb-1638-4366-9022-484d8079c2fd --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-e3293bb\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-e3293bb uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a975405cd5ad\">Q3: Do outdoor tables and benches need to be fixed to the ground?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Not always. Some outdoor furniture is designed as movable furniture, while larger or heavier products may be better placed in fixed positions depending on the site and use requirements.<\/p><p>If the project requires higher stability in open areas, we can discuss whether the furniture should include additional fixing methods or heavier base structures.<!-- notionvc: de520daf-5e36-4511-bb40-eaa4c193a413 --><!-- notionvc: 9abf2f72-f23e-48f8-877c-af58a853e2f7 --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-586ea1e\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-586ea1e uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a975405cd678\">Q4: Can outdoor furniture be assembled on site?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Many outdoor furniture products are shipped either fully assembled or partially assembled depending on size, structure, and shipping requirements. Larger products may require simple on-site assembly to reduce shipping volume and improve packing safety.<\/p><p>We can provide assembly guidance, product photos, or basic installation information when needed.<!-- notionvc: 47597b57-c171-4414-8ec2-c176d1df5cb1 --><!-- notionvc: 985df32f-3005-4cb5-b385-48930cc48fdf --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-f76d69c\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-f76d69c uael-question-span\" tabindex=\"0\" id=\"uael-faq-5-6a975405cd73a\">Q5: What information should I prepare before buying Outdoor Furniture?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>You can prepare the outdoor area size, ground type, climate conditions, preferred product categories, estimated quantity, and any photos of the existing space. These details help us understand how the furniture will be used and what product options may be more suitable.<!-- notionvc: bc48e08d-4800-4a23-ad8e-92f53cb7d661 --><br \/><!-- notionvc: 985df32f-3005-4cb5-b385-48930cc48fdf --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-2086267\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-2086267 uael-question-span\" tabindex=\"0\" id=\"uael-faq-6-6a975405cd7fe\">Q6: Can I request outdoor furniture samples before placing a larger order?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Yes, samples can be arranged for selected outdoor furniture products. This is helpful when you need to check product size, structure, finish quality, packaging, or market response before confirming a larger order.<\/p><p>Sample cost, preparation time, and shipping method will depend on the product type and destination.<\/p><p><!-- notionvc: 6469abf5-ffe4-4c9b-993a-80660143a9c0 --><br \/><!-- notionvc: 985df32f-3005-4cb5-b385-48930cc48fdf --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-4c72034\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-angle-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-4c72034 uael-question-span\" tabindex=\"0\" id=\"uael-faq-7-6a975405cd8de\">Q7: Are replacement parts available for outdoor furniture?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Depending on the product design and order details, replacement parts may be available for certain products. For long-term projects, we recommend confirming your spare parts requirements in advance.<!-- notionvc: d87c07de-e264-421a-83ac-8e4db98eef58 --><br \/><!-- notionvc: 985df32f-3005-4cb5-b385-48930cc48fdf --><\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Outdoor Furniture for Play Spaces We manufacture and supply durable outdoor furniture for children\u2019s learning, play, storage, and daily outdoor activities. We can assist you in selecting the right furniture, customizing details to suit your specific space, and fulfilling your order with comprehensive project support. Weather resistant materials Stable structure Smooth edges and easy clean [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16671","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/pages\/16671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/comments?post=16671"}],"version-history":[{"count":0,"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/pages\/16671\/revisions"}],"wp:attachment":[{"href":"https:\/\/xiairworld.com\/es_mx\/wp-json\/wp\/v2\/media?parent=16671"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}